{"id":77,"count":2,"description":"","link":"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/","name":"Culturales","slug":"culturales","taxonomy":"category","parent":65,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arxius de Culturales - Camper on the road<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arxius de Culturales - Camper on the road\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/\" \/>\n<meta property=\"og:site_name\" content=\"Camper on the road\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/\",\"url\":\"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/\",\"name\":\"Arxius de Culturales - Camper on the road\",\"isPartOf\":{\"@id\":\"https:\/\/www.camperontheroad.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.camperontheroad.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACTIVIDADES\",\"item\":\"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Culturales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.camperontheroad.com\/#website\",\"url\":\"https:\/\/www.camperontheroad.com\/\",\"name\":\"Camper on the road\",\"description\":\"Viajes, Rutas, Road Trip, Camper,\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.camperontheroad.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arxius de Culturales - Camper on the road","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/","og_locale":"es_ES","og_type":"article","og_title":"Arxius de Culturales - Camper on the road","og_url":"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/","og_site_name":"Camper on the road","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/","url":"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/","name":"Arxius de Culturales - Camper on the road","isPartOf":{"@id":"https:\/\/www.camperontheroad.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/culturales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.camperontheroad.com\/"},{"@type":"ListItem","position":2,"name":"ACTIVIDADES","item":"https:\/\/www.camperontheroad.com\/index.php\/category\/actividades\/"},{"@type":"ListItem","position":3,"name":"Culturales"}]},{"@type":"WebSite","@id":"https:\/\/www.camperontheroad.com\/#website","url":"https:\/\/www.camperontheroad.com\/","name":"Camper on the road","description":"Viajes, Rutas, Road Trip, Camper,","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camperontheroad.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.camperontheroad.com\/index.php\/wp-json\/wp\/v2\/categories\/77","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camperontheroad.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.camperontheroad.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.camperontheroad.com\/index.php\/wp-json\/wp\/v2\/categories\/65"}],"wp:post_type":[{"href":"https:\/\/www.camperontheroad.com\/index.php\/wp-json\/wp\/v2\/posts?categories=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}